{"id":605,"date":"2019-01-18T15:45:35","date_gmt":"2019-01-18T15:45:35","guid":{"rendered":"https:\/\/democontent.codex-themes.com\/sites-elementor\/agency-digital\/about-us\/our-process-copy\/"},"modified":"2019-01-18T15:45:35","modified_gmt":"2019-01-18T15:45:35","slug":"services","status":"publish","type":"page","link":"https:\/\/tomatocrust.com\/index.php\/services\/","title":{"rendered":"Services (Demo)"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"605\" class=\"elementor elementor-605\">\n\t\t\t\t\t\t<main class=\"elementor-section elementor-top-section elementor-element elementor-element-161da87 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"161da87\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\r\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-thegem\"><div class=\"elementor-row\">\r\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a4d9e8d\" data-id=\"a4d9e8d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f4c5b88 flex-horizontal-align-default flex-horizontal-align-tablet-default flex-horizontal-align-mobile-default flex-vertical-align-default flex-vertical-align-tablet-default flex-vertical-align-mobile-default elementor-widget elementor-widget-heading\" data-id=\"f4c5b88\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.23.0 - 05-08-2024 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><div class=\"title-h1 elementor-heading-title elementor-size-default\">WE CREATE BEST PRODUCTS<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4ec6183 elementor-widget-divider--view-line flex-horizontal-align-default flex-horizontal-align-tablet-default flex-horizontal-align-mobile-default flex-vertical-align-default flex-vertical-align-tablet-default flex-vertical-align-mobile-default elementor-widget elementor-widget-divider\" data-id=\"4ec6183\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.23.0 - 05-08-2024 *\/\n.elementor-widget-divider{--divider-border-style:none;--divider-border-width:1px;--divider-color:#0c0d0e;--divider-icon-size:20px;--divider-element-spacing:10px;--divider-pattern-height:24px;--divider-pattern-size:20px;--divider-pattern-url:none;--divider-pattern-repeat:repeat-x}.elementor-widget-divider .elementor-divider{display:flex}.elementor-widget-divider .elementor-divider__text{font-size:15px;line-height:1;max-width:95%}.elementor-widget-divider .elementor-divider__element{margin:0 var(--divider-element-spacing);flex-shrink:0}.elementor-widget-divider .elementor-icon{font-size:var(--divider-icon-size)}.elementor-widget-divider .elementor-divider-separator{display:flex;margin:0;direction:ltr}.elementor-widget-divider--view-line_icon .elementor-divider-separator,.elementor-widget-divider--view-line_text .elementor-divider-separator{align-items:center}.elementor-widget-divider--view-line_icon .elementor-divider-separator:after,.elementor-widget-divider--view-line_icon .elementor-divider-separator:before,.elementor-widget-divider--view-line_text .elementor-divider-separator:after,.elementor-widget-divider--view-line_text .elementor-divider-separator:before{display:block;content:\"\";border-block-end:0;flex-grow:1;border-block-start:var(--divider-border-width) var(--divider-border-style) var(--divider-color)}.elementor-widget-divider--element-align-left .elementor-divider .elementor-divider-separator>.elementor-divider__svg:first-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-left .elementor-divider-separator:before{content:none}.elementor-widget-divider--element-align-left .elementor-divider__element{margin-left:0}.elementor-widget-divider--element-align-right .elementor-divider .elementor-divider-separator>.elementor-divider__svg:last-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-right .elementor-divider-separator:after{content:none}.elementor-widget-divider--element-align-right .elementor-divider__element{margin-right:0}.elementor-widget-divider--element-align-start .elementor-divider .elementor-divider-separator>.elementor-divider__svg:first-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-start .elementor-divider-separator:before{content:none}.elementor-widget-divider--element-align-start .elementor-divider__element{margin-inline-start:0}.elementor-widget-divider--element-align-end .elementor-divider .elementor-divider-separator>.elementor-divider__svg:last-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-end .elementor-divider-separator:after{content:none}.elementor-widget-divider--element-align-end .elementor-divider__element{margin-inline-end:0}.elementor-widget-divider:not(.elementor-widget-divider--view-line_text):not(.elementor-widget-divider--view-line_icon) .elementor-divider-separator{border-block-start:var(--divider-border-width) var(--divider-border-style) var(--divider-color)}.elementor-widget-divider--separator-type-pattern{--divider-border-style:none}.elementor-widget-divider--separator-type-pattern.elementor-widget-divider--view-line .elementor-divider-separator,.elementor-widget-divider--separator-type-pattern:not(.elementor-widget-divider--view-line) .elementor-divider-separator:after,.elementor-widget-divider--separator-type-pattern:not(.elementor-widget-divider--view-line) .elementor-divider-separator:before,.elementor-widget-divider--separator-type-pattern:not([class*=elementor-widget-divider--view]) .elementor-divider-separator{width:100%;min-height:var(--divider-pattern-height);-webkit-mask-size:var(--divider-pattern-size) 100%;mask-size:var(--divider-pattern-size) 100%;-webkit-mask-repeat:var(--divider-pattern-repeat);mask-repeat:var(--divider-pattern-repeat);background-color:var(--divider-color);-webkit-mask-image:var(--divider-pattern-url);mask-image:var(--divider-pattern-url)}.elementor-widget-divider--no-spacing{--divider-pattern-size:auto}.elementor-widget-divider--bg-round{--divider-pattern-repeat:round}.rtl .elementor-widget-divider .elementor-divider__text{direction:rtl}.e-con-inner>.elementor-widget-divider,.e-con>.elementor-widget-divider{width:var(--container-widget-width,100%);--flex-grow:var(--container-widget-flex-grow)}<\/style>\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d5a9f8d elementor-widget__width-initial flex-horizontal-align-default flex-horizontal-align-tablet-default flex-horizontal-align-mobile-default flex-vertical-align-default flex-vertical-align-tablet-default flex-vertical-align-mobile-default elementor-widget elementor-widget-heading\" data-id=\"d5a9f8d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"styled-subtitle elementor-heading-title elementor-size-default\">We Always Provide High Quality Products<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a64b5bc flex-horizontal-align-default flex-horizontal-align-tablet-default flex-horizontal-align-mobile-default flex-vertical-align-default flex-vertical-align-tablet-default flex-vertical-align-mobile-default elementor-widget elementor-widget-thegem-quickfinders\" data-id=\"a64b5bc\" data-element_type=\"widget\" data-settings=\"{&quot;thegem_elementor_preset&quot;:&quot;grid-basic-right-align&quot;}\" data-widget_type=\"thegem-quickfinders.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n<div class=\"quickfinder row inline-row quickfinder-style-grid-basic-right-align\">\n\t\t\t<div class=\"lazy-loading  quickfinder-item inline-column col-md-4 col-sm-6 col-xs-12\">\n\n\t\t\t\n\t\t\t\t<div class=\"quickfinder-item-inner icon-top icon-horizontal-right icon-wrapping-inline centered-box button-bottom lazy-loading-item\" data-ll-effect=\"fading\" data-ll-item-delay=\"200\"> \n\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"quickfinder-icon-container\">\n\n\t<div class=\"connector-container\">\n\t\t<span><\/span>\n\t<\/div>\n\n\t<div class=\"gem-qf-icon-image-wrapper lazy-loading-item\" data-ll-effect=\"clip\">\n\t\t\n\t\t\t<div class=\"gem-icon gem-icon-pack-fontawesome gem-icon-size-medium  gem-icon-shape-default\">\n\n\t\t\t\t\n\t\t\t\t<div class=\"icon-hover-bg fade\"><\/div>\n\n\t\t\t\t<div class=\"gem-icon-inner\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"padding-box-inner\">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"gem-icon-half-1\">\n\t\t\t\t\t\t\t\t\t<span class=\"back-angle\">\n\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"gem-mdi mdi-speedometer\"><\/i>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<span class=\"gem-icon-half-2\">\n\t\t\t\t\t\t\t\t\t<span class=\"back-angle\">\n\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"gem-mdi mdi-speedometer\"><\/i>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<\/div>\n\n\t<div class=\"connector-container\">\n\t\t<span><\/span>\n\t<\/div>\n\n<\/div>\n\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"quickfinder-item-info-wrapper\"> \n\t\t\t\t\t\t<div class=\"quickfinder-item-info lazy-loading-item\" data-ll-effect=\"fading\" data-ll-item-delay=\"200\">\n\t\n\t\t<h4 class=\"quickfinder-title title-h4 bold\">\n\t\t\tSPEED OPTIMIZATION\t\t<\/h4>\n\t\n\t\n\t\t<div class=\"quickfinder-description gem-text-output\">\n\t\t\tLorem ipsum dolor sit amet, con secte tur adipi sicing elit, sed do eiusmod tempor incididunt ut labore et dolore\t\t<\/div>\n\t\n\t<\/div>\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<a href=\"#\" target=\"_blank\" rel=\"nofollow\" class=\"quickfinder-item-link\"><\/a>\n\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t<div class=\"lazy-loading  quickfinder-item inline-column col-md-4 col-sm-6 col-xs-12\">\n\n\t\t\t\n\t\t\t\t<div class=\"quickfinder-item-inner icon-top icon-horizontal-right icon-wrapping-inline centered-box button-bottom lazy-loading-item\" data-ll-effect=\"fading\" data-ll-item-delay=\"200\"> \n\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"quickfinder-icon-container\">\n\n\t<div class=\"connector-container\">\n\t\t<span><\/span>\n\t<\/div>\n\n\t<div class=\"gem-qf-icon-image-wrapper lazy-loading-item\" data-ll-effect=\"clip\">\n\t\t\n\t\t\t<div class=\"gem-icon gem-icon-pack-fontawesome gem-icon-size-medium  gem-icon-shape-default\">\n\n\t\t\t\t\n\t\t\t\t<div class=\"icon-hover-bg fade\"><\/div>\n\n\t\t\t\t<div class=\"gem-icon-inner\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"padding-box-inner\">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"gem-icon-half-1\">\n\t\t\t\t\t\t\t\t\t<span class=\"back-angle\">\n\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"gem-mdi mdi-flag-outline-variant\"><\/i>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<span class=\"gem-icon-half-2\">\n\t\t\t\t\t\t\t\t\t<span class=\"back-angle\">\n\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"gem-mdi mdi-flag-outline-variant\"><\/i>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<\/div>\n\n\t<div class=\"connector-container\">\n\t\t<span><\/span>\n\t<\/div>\n\n<\/div>\n\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"quickfinder-item-info-wrapper\"> \n\t\t\t\t\t\t<div class=\"quickfinder-item-info lazy-loading-item\" data-ll-effect=\"fading\" data-ll-item-delay=\"200\">\n\t\n\t\t<h4 class=\"quickfinder-title title-h4 bold\">\n\t\t\tBRANDING RESOURCES\t\t<\/h4>\n\t\n\t\n\t\t<div class=\"quickfinder-description gem-text-output\">\n\t\t\tLorem ipsum dolor sit amet, con secte tur adipi sicing elit, sed do eiusmod tempor incididunt ut labore et dolore\t\t<\/div>\n\t\n\t<\/div>\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<a href=\"#\" target=\"_blank\" rel=\"nofollow\" class=\"quickfinder-item-link\"><\/a>\n\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t<div class=\"lazy-loading  quickfinder-item inline-column col-md-4 col-sm-6 col-xs-12\">\n\n\t\t\t\n\t\t\t\t<div class=\"quickfinder-item-inner icon-top icon-horizontal-right icon-wrapping-inline centered-box button-bottom lazy-loading-item\" data-ll-effect=\"fading\" data-ll-item-delay=\"200\"> \n\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"quickfinder-icon-container\">\n\n\t<div class=\"connector-container\">\n\t\t<span><\/span>\n\t<\/div>\n\n\t<div class=\"gem-qf-icon-image-wrapper lazy-loading-item\" data-ll-effect=\"clip\">\n\t\t\n\t\t\t<div class=\"gem-icon gem-icon-pack-fontawesome gem-icon-size-medium  gem-icon-shape-default\">\n\n\t\t\t\t\n\t\t\t\t<div class=\"icon-hover-bg fade\"><\/div>\n\n\t\t\t\t<div class=\"gem-icon-inner\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"padding-box-inner\">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"gem-icon-half-1\">\n\t\t\t\t\t\t\t\t\t<span class=\"back-angle\">\n\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"gem-mdi mdi-presentation\"><\/i>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<span class=\"gem-icon-half-2\">\n\t\t\t\t\t\t\t\t\t<span class=\"back-angle\">\n\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"gem-mdi mdi-presentation\"><\/i>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<\/div>\n\n\t<div class=\"connector-container\">\n\t\t<span><\/span>\n\t<\/div>\n\n<\/div>\n\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"quickfinder-item-info-wrapper\"> \n\t\t\t\t\t\t<div class=\"quickfinder-item-info lazy-loading-item\" data-ll-effect=\"fading\" data-ll-item-delay=\"200\">\n\t\n\t\t<h4 class=\"quickfinder-title title-h4 bold\">\n\t\t\tDIGITAL MEDIA\t\t<\/h4>\n\t\n\t\n\t\t<div class=\"quickfinder-description gem-text-output\">\n\t\t\tLorem ipsum dolor sit amet, con secte tur adipi sicing elit, sed do eiusmod tempor incididunt ut labore et dolore\t\t<\/div>\n\t\n\t<\/div>\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<a href=\"#\" target=\"_blank\" rel=\"nofollow\" class=\"quickfinder-item-link\"><\/a>\n\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c7dffda flex-horizontal-align-default flex-horizontal-align-tablet-default flex-horizontal-align-mobile-default flex-vertical-align-default flex-vertical-align-tablet-default flex-vertical-align-mobile-default elementor-widget elementor-widget-thegem-quickfinders\" data-id=\"c7dffda\" data-element_type=\"widget\" data-settings=\"{&quot;thegem_elementor_preset&quot;:&quot;grid-basic-right-align&quot;}\" data-widget_type=\"thegem-quickfinders.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n<div class=\"quickfinder row inline-row quickfinder-style-grid-basic-right-align\">\n\t\t\t<div class=\"lazy-loading  quickfinder-item inline-column col-md-4 col-sm-6 col-xs-12\">\n\n\t\t\t\n\t\t\t\t<div class=\"quickfinder-item-inner icon-top icon-horizontal-right icon-wrapping-inline centered-box button-bottom lazy-loading-item\" data-ll-effect=\"fading\" data-ll-item-delay=\"200\"> \n\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"quickfinder-icon-container\">\n\n\t<div class=\"connector-container\">\n\t\t<span><\/span>\n\t<\/div>\n\n\t<div class=\"gem-qf-icon-image-wrapper lazy-loading-item\" data-ll-effect=\"clip\">\n\t\t\n\t\t\t<div class=\"gem-icon gem-icon-pack-fontawesome gem-icon-size-medium  gem-icon-shape-default\">\n\n\t\t\t\t\n\t\t\t\t<div class=\"icon-hover-bg fade\"><\/div>\n\n\t\t\t\t<div class=\"gem-icon-inner\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"padding-box-inner\">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"gem-icon-half-1\">\n\t\t\t\t\t\t\t\t\t<span class=\"back-angle\">\n\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"gem-mdi mdi-chart-line\"><\/i>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<span class=\"gem-icon-half-2\">\n\t\t\t\t\t\t\t\t\t<span class=\"back-angle\">\n\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"gem-mdi mdi-chart-line\"><\/i>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<\/div>\n\n\t<div class=\"connector-container\">\n\t\t<span><\/span>\n\t<\/div>\n\n<\/div>\n\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"quickfinder-item-info-wrapper\"> \n\t\t\t\t\t\t<div class=\"quickfinder-item-info lazy-loading-item\" data-ll-effect=\"fading\" data-ll-item-delay=\"200\">\n\t\n\t\t<h4 class=\"quickfinder-title title-h4 bold\">\n\t\t\tMARKET ANALYSIS\t\t<\/h4>\n\t\n\t\n\t\t<div class=\"quickfinder-description gem-text-output\">\n\t\t\tLorem ipsum dolor sit amet, con secte tur adipi sicing elit, sed do eiusmod tempor incididunt ut labore et dolore\t\t<\/div>\n\t\n\t<\/div>\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<a href=\"#\" target=\"_blank\" rel=\"nofollow\" class=\"quickfinder-item-link\"><\/a>\n\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t<div class=\"lazy-loading  quickfinder-item inline-column col-md-4 col-sm-6 col-xs-12\">\n\n\t\t\t\n\t\t\t\t<div class=\"quickfinder-item-inner icon-top icon-horizontal-right icon-wrapping-inline centered-box button-bottom lazy-loading-item\" data-ll-effect=\"fading\" data-ll-item-delay=\"200\"> \n\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"quickfinder-icon-container\">\n\n\t<div class=\"connector-container\">\n\t\t<span><\/span>\n\t<\/div>\n\n\t<div class=\"gem-qf-icon-image-wrapper lazy-loading-item\" data-ll-effect=\"clip\">\n\t\t\n\t\t\t<div class=\"gem-icon gem-icon-pack-fontawesome gem-icon-size-medium  gem-icon-shape-default\">\n\n\t\t\t\t\n\t\t\t\t<div class=\"icon-hover-bg fade\"><\/div>\n\n\t\t\t\t<div class=\"gem-icon-inner\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"padding-box-inner\">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"gem-icon-half-1\">\n\t\t\t\t\t\t\t\t\t<span class=\"back-angle\">\n\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"gem-mdi mdi-cube-unfolded\"><\/i>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<span class=\"gem-icon-half-2\">\n\t\t\t\t\t\t\t\t\t<span class=\"back-angle\">\n\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"gem-mdi mdi-cube-unfolded\"><\/i>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<\/div>\n\n\t<div class=\"connector-container\">\n\t\t<span><\/span>\n\t<\/div>\n\n<\/div>\n\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"quickfinder-item-info-wrapper\"> \n\t\t\t\t\t\t<div class=\"quickfinder-item-info lazy-loading-item\" data-ll-effect=\"fading\" data-ll-item-delay=\"200\">\n\t\n\t\t<h4 class=\"quickfinder-title title-h4 bold\">\n\t\t\tWEB SOLUTION\t\t<\/h4>\n\t\n\t\n\t\t<div class=\"quickfinder-description gem-text-output\">\n\t\t\tLorem ipsum dolor sit amet, con secte tur adipi sicing elit, sed do eiusmod tempor incididunt ut labore et dolore\t\t<\/div>\n\t\n\t<\/div>\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<a href=\"#\" target=\"_blank\" rel=\"nofollow\" class=\"quickfinder-item-link\"><\/a>\n\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t<div class=\"lazy-loading  quickfinder-item inline-column col-md-4 col-sm-6 col-xs-12\">\n\n\t\t\t\n\t\t\t\t<div class=\"quickfinder-item-inner icon-top icon-horizontal-right icon-wrapping-inline centered-box button-bottom lazy-loading-item\" data-ll-effect=\"fading\" data-ll-item-delay=\"200\"> \n\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"quickfinder-icon-container\">\n\n\t<div class=\"connector-container\">\n\t\t<span><\/span>\n\t<\/div>\n\n\t<div class=\"gem-qf-icon-image-wrapper lazy-loading-item\" data-ll-effect=\"clip\">\n\t\t\n\t\t\t<div class=\"gem-icon gem-icon-pack-fontawesome gem-icon-size-medium  gem-icon-shape-default\">\n\n\t\t\t\t\n\t\t\t\t<div class=\"icon-hover-bg fade\"><\/div>\n\n\t\t\t\t<div class=\"gem-icon-inner\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"padding-box-inner\">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"gem-icon-half-1\">\n\t\t\t\t\t\t\t\t\t<span class=\"back-angle\">\n\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"gem-mdi mdi-monitor\"><\/i>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<span class=\"gem-icon-half-2\">\n\t\t\t\t\t\t\t\t\t<span class=\"back-angle\">\n\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"gem-mdi mdi-monitor\"><\/i>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<\/div>\n\n\t<div class=\"connector-container\">\n\t\t<span><\/span>\n\t<\/div>\n\n<\/div>\n\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"quickfinder-item-info-wrapper\"> \n\t\t\t\t\t\t<div class=\"quickfinder-item-info lazy-loading-item\" data-ll-effect=\"fading\" data-ll-item-delay=\"200\">\n\t\n\t\t<h4 class=\"quickfinder-title title-h4 bold\">\n\t\t\tWEB DEVELOPMENT\t\t<\/h4>\n\t\n\t\n\t\t<div class=\"quickfinder-description gem-text-output\">\n\t\t\tLorem ipsum dolor sit amet, con secte tur adipi sicing elit, sed do eiusmod tempor incididunt ut labore et dolore\t\t<\/div>\n\t\n\t<\/div>\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<a href=\"#\" target=\"_blank\" rel=\"nofollow\" class=\"quickfinder-item-link\"><\/a>\n\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-163bab1 flex-horizontal-align-default flex-horizontal-align-tablet-default flex-horizontal-align-mobile-default flex-vertical-align-default flex-vertical-align-tablet-default flex-vertical-align-mobile-default elementor-widget elementor-widget-thegem-quickfinders\" data-id=\"163bab1\" data-element_type=\"widget\" data-settings=\"{&quot;thegem_elementor_preset&quot;:&quot;grid-basic-right-align&quot;}\" data-widget_type=\"thegem-quickfinders.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n<div class=\"quickfinder row inline-row quickfinder-style-grid-basic-right-align\">\n\t\t\t<div class=\"lazy-loading  quickfinder-item inline-column col-md-4 col-sm-6 col-xs-12\">\n\n\t\t\t\n\t\t\t\t<div class=\"quickfinder-item-inner icon-top icon-horizontal-right icon-wrapping-inline centered-box button-bottom lazy-loading-item\" data-ll-effect=\"fading\" data-ll-item-delay=\"200\"> \n\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"quickfinder-icon-container\">\n\n\t<div class=\"connector-container\">\n\t\t<span><\/span>\n\t<\/div>\n\n\t<div class=\"gem-qf-icon-image-wrapper lazy-loading-item\" data-ll-effect=\"clip\">\n\t\t\n\t\t\t<div class=\"gem-icon gem-icon-pack-fontawesome gem-icon-size-medium  gem-icon-shape-default\">\n\n\t\t\t\t\n\t\t\t\t<div class=\"icon-hover-bg fade\"><\/div>\n\n\t\t\t\t<div class=\"gem-icon-inner\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"padding-box-inner\">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"gem-icon-half-1\">\n\t\t\t\t\t\t\t\t\t<span class=\"back-angle\">\n\t\t\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-cog\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M487.4 315.7l-42.6-24.6c4.3-23.2 4.3-47 0-70.2l42.6-24.6c4.9-2.8 7.1-8.6 5.5-14-11.1-35.6-30-67.8-54.7-94.6-3.8-4.1-10-5.1-14.8-2.3L380.8 110c-17.9-15.4-38.5-27.3-60.8-35.1V25.8c0-5.6-3.9-10.5-9.4-11.7-36.7-8.2-74.3-7.8-109.2 0-5.5 1.2-9.4 6.1-9.4 11.7V75c-22.2 7.9-42.8 19.8-60.8 35.1L88.7 85.5c-4.9-2.8-11-1.9-14.8 2.3-24.7 26.7-43.6 58.9-54.7 94.6-1.7 5.4.6 11.2 5.5 14L67.3 221c-4.3 23.2-4.3 47 0 70.2l-42.6 24.6c-4.9 2.8-7.1 8.6-5.5 14 11.1 35.6 30 67.8 54.7 94.6 3.8 4.1 10 5.1 14.8 2.3l42.6-24.6c17.9 15.4 38.5 27.3 60.8 35.1v49.2c0 5.6 3.9 10.5 9.4 11.7 36.7 8.2 74.3 7.8 109.2 0 5.5-1.2 9.4-6.1 9.4-11.7v-49.2c22.2-7.9 42.8-19.8 60.8-35.1l42.6 24.6c4.9 2.8 11 1.9 14.8-2.3 24.7-26.7 43.6-58.9 54.7-94.6 1.5-5.5-.7-11.3-5.6-14.1zM256 336c-44.1 0-80-35.9-80-80s35.9-80 80-80 80 35.9 80 80-35.9 80-80 80z\"><\/path><\/svg>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<span class=\"gem-icon-half-2\">\n\t\t\t\t\t\t\t\t\t<span class=\"back-angle\">\n\t\t\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-cog\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M487.4 315.7l-42.6-24.6c4.3-23.2 4.3-47 0-70.2l42.6-24.6c4.9-2.8 7.1-8.6 5.5-14-11.1-35.6-30-67.8-54.7-94.6-3.8-4.1-10-5.1-14.8-2.3L380.8 110c-17.9-15.4-38.5-27.3-60.8-35.1V25.8c0-5.6-3.9-10.5-9.4-11.7-36.7-8.2-74.3-7.8-109.2 0-5.5 1.2-9.4 6.1-9.4 11.7V75c-22.2 7.9-42.8 19.8-60.8 35.1L88.7 85.5c-4.9-2.8-11-1.9-14.8 2.3-24.7 26.7-43.6 58.9-54.7 94.6-1.7 5.4.6 11.2 5.5 14L67.3 221c-4.3 23.2-4.3 47 0 70.2l-42.6 24.6c-4.9 2.8-7.1 8.6-5.5 14 11.1 35.6 30 67.8 54.7 94.6 3.8 4.1 10 5.1 14.8 2.3l42.6-24.6c17.9 15.4 38.5 27.3 60.8 35.1v49.2c0 5.6 3.9 10.5 9.4 11.7 36.7 8.2 74.3 7.8 109.2 0 5.5-1.2 9.4-6.1 9.4-11.7v-49.2c22.2-7.9 42.8-19.8 60.8-35.1l42.6 24.6c4.9 2.8 11 1.9 14.8-2.3 24.7-26.7 43.6-58.9 54.7-94.6 1.5-5.5-.7-11.3-5.6-14.1zM256 336c-44.1 0-80-35.9-80-80s35.9-80 80-80 80 35.9 80 80-35.9 80-80 80z\"><\/path><\/svg>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<\/div>\n\n\t<div class=\"connector-container\">\n\t\t<span><\/span>\n\t<\/div>\n\n<\/div>\n\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"quickfinder-item-info-wrapper\"> \n\t\t\t\t\t\t<div class=\"quickfinder-item-info lazy-loading-item\" data-ll-effect=\"fading\" data-ll-item-delay=\"200\">\n\t\n\t\t<h4 class=\"quickfinder-title title-h4 bold\">\n\t\t\tUSER EXPERIENCE\t\t<\/h4>\n\t\n\t\n\t\t<div class=\"quickfinder-description gem-text-output\">\n\t\t\tLorem ipsum dolor sit amet, con secte tur adipi sicing elit, sed do eiusmod tempor incididunt ut labore et dolore\t\t<\/div>\n\t\n\t<\/div>\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<a href=\"#\" target=\"_blank\" rel=\"nofollow\" class=\"quickfinder-item-link\"><\/a>\n\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t<div class=\"lazy-loading  quickfinder-item inline-column col-md-4 col-sm-6 col-xs-12\">\n\n\t\t\t\n\t\t\t\t<div class=\"quickfinder-item-inner icon-top icon-horizontal-right icon-wrapping-inline centered-box button-bottom lazy-loading-item\" data-ll-effect=\"fading\" data-ll-item-delay=\"200\"> \n\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"quickfinder-icon-container\">\n\n\t<div class=\"connector-container\">\n\t\t<span><\/span>\n\t<\/div>\n\n\t<div class=\"gem-qf-icon-image-wrapper lazy-loading-item\" data-ll-effect=\"clip\">\n\t\t\n\t\t\t<div class=\"gem-icon gem-icon-pack-fontawesome gem-icon-size-medium  gem-icon-shape-default\">\n\n\t\t\t\t\n\t\t\t\t<div class=\"icon-hover-bg fade\"><\/div>\n\n\t\t\t\t<div class=\"gem-icon-inner\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"padding-box-inner\">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"gem-icon-half-1\">\n\t\t\t\t\t\t\t\t\t<span class=\"back-angle\">\n\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"gem-mdi mdi-television-guide\"><\/i>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<span class=\"gem-icon-half-2\">\n\t\t\t\t\t\t\t\t\t<span class=\"back-angle\">\n\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"gem-mdi mdi-television-guide\"><\/i>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<\/div>\n\n\t<div class=\"connector-container\">\n\t\t<span><\/span>\n\t<\/div>\n\n<\/div>\n\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"quickfinder-item-info-wrapper\"> \n\t\t\t\t\t\t<div class=\"quickfinder-item-info lazy-loading-item\" data-ll-effect=\"fading\" data-ll-item-delay=\"200\">\n\t\n\t\t<h4 class=\"quickfinder-title title-h4 bold\">\n\t\t\tUSER INTERFACE\t\t<\/h4>\n\t\n\t\n\t\t<div class=\"quickfinder-description gem-text-output\">\n\t\t\tLorem ipsum dolor sit amet, con secte tur adipi sicing elit, sed do eiusmod tempor incididunt ut labore et dolore\t\t<\/div>\n\t\n\t<\/div>\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<a href=\"#\" target=\"_blank\" rel=\"nofollow\" class=\"quickfinder-item-link\"><\/a>\n\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t<div class=\"lazy-loading  quickfinder-item inline-column col-md-4 col-sm-6 col-xs-12\">\n\n\t\t\t\n\t\t\t\t<div class=\"quickfinder-item-inner icon-top icon-horizontal-right icon-wrapping-inline centered-box button-bottom lazy-loading-item\" data-ll-effect=\"fading\" data-ll-item-delay=\"200\"> \n\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"quickfinder-icon-container\">\n\n\t<div class=\"connector-container\">\n\t\t<span><\/span>\n\t<\/div>\n\n\t<div class=\"gem-qf-icon-image-wrapper lazy-loading-item\" data-ll-effect=\"clip\">\n\t\t\n\t\t\t<div class=\"gem-icon gem-icon-pack-fontawesome gem-icon-size-medium  gem-icon-shape-default\">\n\n\t\t\t\t\n\t\t\t\t<div class=\"icon-hover-bg fade\"><\/div>\n\n\t\t\t\t<div class=\"gem-icon-inner\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"padding-box-inner\">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"gem-icon-half-1\">\n\t\t\t\t\t\t\t\t\t<span class=\"back-angle\">\n\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"gem-mdi mdi-coin\"><\/i>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<span class=\"gem-icon-half-2\">\n\t\t\t\t\t\t\t\t\t<span class=\"back-angle\">\n\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"gem-mdi mdi-coin\"><\/i>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<\/div>\n\n\t<div class=\"connector-container\">\n\t\t<span><\/span>\n\t<\/div>\n\n<\/div>\n\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"quickfinder-item-info-wrapper\"> \n\t\t\t\t\t\t<div class=\"quickfinder-item-info lazy-loading-item\" data-ll-effect=\"fading\" data-ll-item-delay=\"200\">\n\t\n\t\t<h4 class=\"quickfinder-title title-h4 bold\">\n\t\t\tFINANCIAL ADVICE\t\t<\/h4>\n\t\n\t\n\t\t<div class=\"quickfinder-description gem-text-output\">\n\t\t\tLorem ipsum dolor sit amet, con secte tur adipi sicing elit, sed do eiusmod tempor incididunt ut labore et dolore\t\t<\/div>\n\t\n\t<\/div>\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<a href=\"#\" target=\"_blank\" rel=\"nofollow\" class=\"quickfinder-item-link\"><\/a>\n\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div><\/div>\r\n\t\t<\/main>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c98f1ed elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"c98f1ed\" data-element_type=\"section\">\r\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\"><div class=\"elementor-row\">\r\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5796576\" data-id=\"5796576\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-802c8a3 flex-horizontal-align-default flex-horizontal-align-tablet-default flex-horizontal-align-mobile-default flex-vertical-align-default flex-vertical-align-tablet-default flex-vertical-align-mobile-default elementor-invisible elementor-widget elementor-widget-thegem-styled-textbox\" data-id=\"802c8a3\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;thegem_elementor_preset&quot;:&quot;basic&quot;}\" data-widget_type=\"thegem-styled-textbox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n<div class=\"gem-textbox styled-textbox-basic\">\n\n\t\n\t\t<div class=\"gem-textbox-top gem-textbox-top-none default-fill\">\n\t\t\t\t\t<\/div>\n\t\n\t<div class=\"gem-textbox-inner\">\n\n\t\t<div class=\"gem-textbox-content default-background icon-top gem-textbox-icon-image-wrapping-none\">\n\n\t\t\t\t\t\t\t<div class=\"gem-texbox-icon-image-wrapper\">\n\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"icon-top \">\n\t\t\t\t\t\t\t<div class=\"gem-textbox-icon\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-icon\">\n\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"gem-mdi mdi-trophy\"><\/i>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"gem-texbox-text-wrapper\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<h4 class=\"gem-textbox-title title-h4 bold\">\n\t\t\t\t\t\t\tGREAT INSPIRATION\t\t\t\t\t\t<\/h4>\n\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"gem-textbox-description gem-text-output\">\n\t\t\t\t\t\t\t<div class=\"styled-subtitle\">Duis sed odio sit amet nibh vulputate cursus a sit amet mauris. Morbi accumsan ipsum<\/div>\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t<\/div>\n\n\t<\/div>\n\n\t\n\t\t<div class=\"gem-textbox-bottom gem-textbox-bottom-none default-fill\">\n\t\t\t\t<\/div>\n\t\n\t\n<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-a00cfce\" data-id=\"a00cfce\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-96ad056 flex-horizontal-align-default flex-horizontal-align-tablet-default flex-horizontal-align-mobile-default flex-vertical-align-default flex-vertical-align-tablet-default flex-vertical-align-mobile-default elementor-invisible elementor-widget elementor-widget-thegem-styled-textbox\" data-id=\"96ad056\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;thegem_elementor_preset&quot;:&quot;basic&quot;}\" data-widget_type=\"thegem-styled-textbox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n<div class=\"gem-textbox styled-textbox-basic\">\n\n\t\n\t\t<div class=\"gem-textbox-top gem-textbox-top-none default-fill\">\n\t\t\t\t\t<\/div>\n\t\n\t<div class=\"gem-textbox-inner\">\n\n\t\t<div class=\"gem-textbox-content default-background icon-top gem-textbox-icon-image-wrapping-none\">\n\n\t\t\t\t\t\t\t<div class=\"gem-texbox-icon-image-wrapper\">\n\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"icon-top \">\n\t\t\t\t\t\t\t<div class=\"gem-textbox-icon\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-icon\">\n\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"gem-mdi mdi-cube-unfolded\"><\/i>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"gem-texbox-text-wrapper\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<h4 class=\"gem-textbox-title title-h4 bold\">\n\t\t\t\t\t\t\tCUSTOMER FOCUSED\t\t\t\t\t\t<\/h4>\n\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"gem-textbox-description gem-text-output\">\n\t\t\t\t\t\t\t<div class=\"styled-subtitle\">Duis sed odio sit amet nibh vulputate cursus a sit amet mauris. Morbi accumsan ipsum<\/div>\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t<\/div>\n\n\t<\/div>\n\n\t\n\t\t<div class=\"gem-textbox-bottom gem-textbox-bottom-none default-fill\">\n\t\t\t\t<\/div>\n\t\n\t\n<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1e6f165\" data-id=\"1e6f165\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9666b43 flex-horizontal-align-default flex-horizontal-align-tablet-default flex-horizontal-align-mobile-default flex-vertical-align-default flex-vertical-align-tablet-default flex-vertical-align-mobile-default elementor-invisible elementor-widget elementor-widget-thegem-styled-textbox\" data-id=\"9666b43\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;thegem_elementor_preset&quot;:&quot;basic&quot;}\" data-widget_type=\"thegem-styled-textbox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n<div class=\"gem-textbox styled-textbox-basic\">\n\n\t\n\t\t<div class=\"gem-textbox-top gem-textbox-top-none default-fill\">\n\t\t\t\t\t<\/div>\n\t\n\t<div class=\"gem-textbox-inner\">\n\n\t\t<div class=\"gem-textbox-content default-background icon-top gem-textbox-icon-image-wrapping-none\">\n\n\t\t\t\t\t\t\t<div class=\"gem-texbox-icon-image-wrapper\">\n\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"icon-top \">\n\t\t\t\t\t\t\t<div class=\"gem-textbox-icon\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-icon\">\n\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"gem-mdi mdi-presentation\"><\/i>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"gem-texbox-text-wrapper\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<h4 class=\"gem-textbox-title title-h4 bold\">\n\t\t\t\t\t\t\tBRAND CONSULTING\t\t\t\t\t\t<\/h4>\n\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"gem-textbox-description gem-text-output\">\n\t\t\t\t\t\t\t<div class=\"styled-subtitle\">Duis sed odio sit amet nibh vulputate cursus a sit amet mauris. Morbi accumsan ipsum<\/div>\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t<\/div>\n\n\t<\/div>\n\n\t\n\t\t<div class=\"gem-textbox-bottom gem-textbox-bottom-none default-fill\">\n\t\t\t\t<\/div>\n\t\n\t\n<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div><\/div>\r\n\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-aa5776c elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"aa5776c\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\r\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-thegem\"><div class=\"elementor-row\">\r\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-ebe29dc\" data-id=\"ebe29dc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e8cf670 flex-horizontal-align-default flex-horizontal-align-tablet-default flex-horizontal-align-mobile-default flex-vertical-align-default flex-vertical-align-tablet-default flex-vertical-align-mobile-default elementor-widget elementor-widget-text-editor\" data-id=\"e8cf670\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.23.0 - 05-08-2024 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\r\n\t\t\t\t\t\t<p>Lorem Ipsum proin gravida nibh vel velit auctor aliquet. Aenean sollicitudin, lorem quis bibendum auctor, nisi elit consequat ipsum, nec sagittis sem nibh id elit. Duis sed odio sit amet nibh vulputate cursus a sit amet mauris. Morbi accumsan ipsum velit. Nam nec tellus a odio tincidunt auctor a ornare odio. Sed non mauris vitae erat consequat.<\/p><p>Class aptent taciti sociosqu ad litora torquent per conubia nostra, per inceptos himenaeos. Mauris in erat justo. Nullam ac urna eu felis dapibus condimentum sit amet a augue. Sed non neque elit. Sed ut imperdiet nisi. Proin condimentum fermentum nunc. Etiam pharetra, erat sed fermentum feugiat, velit mauris egestas quam, ut aliquam massa nisl quis neque.<\/p><p>Suspendisse in orci enim. Duis sed odio sit amet nibh vulputate cursus a sit amet mauris. Morbi accumsan ipsum velit. Nam nec tellus a odio tincidunt auctor a ornare odio. Sed non mauris vitae erat consequat auctor eu in elit. Class aptent taciti sociosqu ad litora torquent per conubia nostra, per inceptos himenaeos.<br \/>Mauris in erat justo. Nullam ac urna eu felis dapibus condimentum sit amet a augue.<\/p>\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-25fe0ca\" data-id=\"25fe0ca\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4d3fd70 flex-horizontal-align-default flex-horizontal-align-tablet-default flex-horizontal-align-mobile-default flex-vertical-align-default flex-vertical-align-tablet-default flex-vertical-align-mobile-default elementor-invisible elementor-widget elementor-widget-image\" data-id=\"4d3fd70\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.23.0 - 05-08-2024 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t<img width=\"423\" height=\"423\" src=\"https:\/\/tomatocrust.com\/wp-content\/uploads\/2020\/05\/noname.png\" class=\"attachment-large size-large wp-image-2135\" alt=\"\" srcset=\"https:\/\/tomatocrust.com\/wp-content\/uploads\/2020\/05\/noname.png 423w, https:\/\/tomatocrust.com\/wp-content\/uploads\/2020\/05\/noname-300x300.png 300w, https:\/\/tomatocrust.com\/wp-content\/uploads\/2020\/05\/noname-150x150.png 150w, https:\/\/tomatocrust.com\/wp-content\/uploads\/2020\/05\/noname-256x256.png 256w\" sizes=\"(max-width: 423px) 100vw, 423px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-3ca0753\" data-id=\"3ca0753\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bf5c1e9 elementor-widget-tablet__width-auto elementor-icon-list--layout-traditional elementor-list-item-link-full_width flex-horizontal-align-default flex-horizontal-align-tablet-default flex-horizontal-align-mobile-default flex-vertical-align-default flex-vertical-align-tablet-default flex-vertical-align-mobile-default elementor-widget elementor-widget-icon-list\" data-id=\"bf5c1e9\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/tomatocrust.com\/wp-content\/plugins\/elementor\/assets\/css\/widget-icon-list.min.css\">\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-square\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M400 32H48C21.5 32 0 53.5 0 80v352c0 26.5 21.5 48 48 48h352c26.5 0 48-21.5 48-48V80c0-26.5-21.5-48-48-48z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Yes<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-10858c4 elementor-widget-tablet__width-auto elementor-icon-list--layout-traditional elementor-list-item-link-full_width flex-horizontal-align-default flex-horizontal-align-tablet-default flex-horizontal-align-mobile-default flex-vertical-align-default flex-vertical-align-tablet-default flex-vertical-align-mobile-default elementor-widget elementor-widget-icon-list\" data-id=\"10858c4\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-square\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M400 32H48C21.5 32 0 53.5 0 80v352c0 26.5 21.5 48 48 48h352c26.5 0 48-21.5 48-48V80c0-26.5-21.5-48-48-48z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">No<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div><\/div>\r\n\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7cd1b4f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7cd1b4f\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\r\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-thegem\"><div class=\"elementor-row\">\r\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2e45614\" data-id=\"2e45614\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4adc783 flex-horizontal-align-default flex-horizontal-align-tablet-default flex-horizontal-align-mobile-default flex-vertical-align-default flex-vertical-align-tablet-default flex-vertical-align-mobile-default elementor-widget elementor-widget-heading\" data-id=\"4adc783\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"title-h1 elementor-heading-title elementor-size-default\">WHAT WE STAND FOR?<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1467a0e elementor-widget-divider--view-line flex-horizontal-align-default flex-horizontal-align-tablet-default flex-horizontal-align-mobile-default flex-vertical-align-default flex-vertical-align-tablet-default flex-vertical-align-mobile-default elementor-widget elementor-widget-divider\" data-id=\"1467a0e\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-261f6ef elementor-widget__width-initial flex-horizontal-align-default flex-horizontal-align-tablet-default flex-horizontal-align-mobile-default flex-vertical-align-default flex-vertical-align-tablet-default flex-vertical-align-mobile-default elementor-widget elementor-widget-heading\" data-id=\"261f6ef\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"styled-subtitle elementor-heading-title elementor-size-default\">Lorem ipsum dolor sit amet, consectetur adipisicing elit,\nsed do eiusmod tempor incididunt ut labore et dolore<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d9a2f63 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d9a2f63\" data-element_type=\"section\">\r\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-thegem\"><div class=\"elementor-row\">\r\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-0e6daae\" data-id=\"0e6daae\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ab0f82f flex-horizontal-align-default flex-horizontal-align-tablet-default flex-horizontal-align-mobile-default flex-vertical-align-default flex-vertical-align-tablet-default flex-vertical-align-mobile-default elementor-widget elementor-widget-heading\" data-id=\"ab0f82f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"title-xlarge elementor-heading-title elementor-size-default\">01<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-828b93d flex-horizontal-align-default flex-horizontal-align-tablet-default flex-horizontal-align-mobile-default flex-vertical-align-default flex-vertical-align-tablet-default flex-vertical-align-mobile-default elementor-widget elementor-widget-thegem-icon\" data-id=\"828b93d\" data-element_type=\"widget\" data-settings=\"{&quot;thegem_elementor_preset&quot;:&quot;default&quot;}\" data-widget_type=\"thegem-icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"centered-box icon-inline-position\">\n\n\t\t\t\t<a >\n\n\t\t\t\t<div class=\"gem-icon gem-icon-pack-fontawesome gem-icon-size-medium  gem-icon-shape-default \">\n\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"gem-icon-inner\">\t\t\t\t\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"padding-box-inner\">\t\n\t\t\t\t\t\t\t\t\t\t\t\n\n\n\t\t\t\t\t\n\t\t\t\t\t<span class=\"gem-icon-half-1\"><span class=\"back-angle\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"gem-elegant icon-pens-alt\"><\/i>\t\t\t\t\t<\/span><\/span>\n\t\t\t\t\t<span class=\"gem-icon-half-2\"><span class=\"back-angle\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"gem-elegant icon-pens-alt\"><\/i>\t\t\t\t\t<\/span><\/span>\t\n\t\t\t\t\n\t\t\t\t<\/div>\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t<\/div>\n\n\t\t\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e58f088 flex-horizontal-align-default flex-horizontal-align-tablet-default flex-horizontal-align-mobile-default flex-vertical-align-default flex-vertical-align-tablet-default flex-vertical-align-mobile-default elementor-widget elementor-widget-heading\" data-id=\"e58f088\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"title-h6 elementor-heading-title elementor-size-default\">Mission<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-03a5ba3 flex-horizontal-align-default flex-horizontal-align-tablet-default flex-horizontal-align-mobile-default flex-vertical-align-default flex-vertical-align-tablet-default flex-vertical-align-mobile-default elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"03a5ba3\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\r\n\t\t\t\t\t\t<p>Lorem ipsum dolor sit amet, consectetur adipisicing elit, sed do eiusmod tempor incididunt ut labore et dolore.<\/p>\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6c46df2 flex-horizontal-align-default flex-horizontal-align-tablet-default flex-horizontal-align-mobile-default flex-vertical-align-default flex-vertical-align-tablet-default flex-vertical-align-mobile-default elementor-widget elementor-widget-spacer\" data-id=\"6c46df2\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.23.0 - 05-08-2024 *\/\n.elementor-column .elementor-spacer-inner{height:var(--spacer-size)}.e-con{--container-widget-width:100%}.e-con-inner>.elementor-widget-spacer,.e-con>.elementor-widget-spacer{width:var(--container-widget-width,var(--spacer-size));--align-self:var(--container-widget-align-self,initial);--flex-shrink:0}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container,.e-con>.elementor-widget-spacer>.elementor-widget-container{height:100%;width:100%}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer{height:100%}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner{height:var(--container-widget-height,var(--spacer-size))}.e-con-inner>.elementor-widget-spacer.elementor-widget-empty,.e-con>.elementor-widget-spacer.elementor-widget-empty{position:relative;min-height:22px;min-width:22px}.e-con-inner>.elementor-widget-spacer.elementor-widget-empty .elementor-widget-empty-icon,.e-con>.elementor-widget-spacer.elementor-widget-empty .elementor-widget-empty-icon{position:absolute;top:0;bottom:0;left:0;right:0;margin:auto;padding:0;width:22px;height:22px}<\/style>\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-64e609d\" data-id=\"64e609d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d906223 flex-horizontal-align-default flex-horizontal-align-tablet-default flex-horizontal-align-mobile-default flex-vertical-align-default flex-vertical-align-tablet-default flex-vertical-align-mobile-default elementor-widget elementor-widget-heading\" data-id=\"d906223\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"title-xlarge elementor-heading-title elementor-size-default\">02<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7c1c498 flex-horizontal-align-default flex-horizontal-align-tablet-default flex-horizontal-align-mobile-default flex-vertical-align-default flex-vertical-align-tablet-default flex-vertical-align-mobile-default elementor-widget elementor-widget-thegem-icon\" data-id=\"7c1c498\" data-element_type=\"widget\" data-settings=\"{&quot;thegem_elementor_preset&quot;:&quot;default&quot;}\" data-widget_type=\"thegem-icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"centered-box icon-inline-position\">\n\n\t\t\t\t<a >\n\n\t\t\t\t<div class=\"gem-icon gem-icon-pack-fontawesome gem-icon-size-medium  gem-icon-shape-default \">\n\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"gem-icon-inner\">\t\t\t\t\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"padding-box-inner\">\t\n\t\t\t\t\t\t\t\t\t\t\t\n\n\n\t\t\t\t\t\n\t\t\t\t\t<span class=\"gem-icon-half-1\"><span class=\"back-angle\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"gem-elegant icon-lightbulb-alt\"><\/i>\t\t\t\t\t<\/span><\/span>\n\t\t\t\t\t<span class=\"gem-icon-half-2\"><span class=\"back-angle\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"gem-elegant icon-lightbulb-alt\"><\/i>\t\t\t\t\t<\/span><\/span>\t\n\t\t\t\t\n\t\t\t\t<\/div>\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t<\/div>\n\n\t\t\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-714131a flex-horizontal-align-default flex-horizontal-align-tablet-default flex-horizontal-align-mobile-default flex-vertical-align-default flex-vertical-align-tablet-default flex-vertical-align-mobile-default elementor-widget elementor-widget-heading\" data-id=\"714131a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"title-h6 elementor-heading-title elementor-size-default\">Vision<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-79514ae flex-horizontal-align-default flex-horizontal-align-tablet-default flex-horizontal-align-mobile-default flex-vertical-align-default flex-vertical-align-tablet-default flex-vertical-align-mobile-default elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"79514ae\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\r\n\t\t\t\t\t\t<p>Lorem ipsum dolor sit amet, consectetur adipisicing elit, sed do eiusmod tempor incididunt ut labore et dolore.<\/p>\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a876bf4 flex-horizontal-align-default flex-horizontal-align-tablet-default flex-horizontal-align-mobile-default flex-vertical-align-default flex-vertical-align-tablet-default flex-vertical-align-mobile-default elementor-widget elementor-widget-spacer\" data-id=\"a876bf4\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-cb46f1b\" data-id=\"cb46f1b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cf4e5f7 flex-horizontal-align-default flex-horizontal-align-tablet-default flex-horizontal-align-mobile-default flex-vertical-align-default flex-vertical-align-tablet-default flex-vertical-align-mobile-default elementor-widget elementor-widget-heading\" data-id=\"cf4e5f7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"title-xlarge elementor-heading-title elementor-size-default\">03<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-694a88d flex-horizontal-align-default flex-horizontal-align-tablet-default flex-horizontal-align-mobile-default flex-vertical-align-default flex-vertical-align-tablet-default flex-vertical-align-mobile-default elementor-widget elementor-widget-thegem-icon\" data-id=\"694a88d\" data-element_type=\"widget\" data-settings=\"{&quot;thegem_elementor_preset&quot;:&quot;default&quot;}\" data-widget_type=\"thegem-icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"centered-box icon-inline-position\">\n\n\t\t\t\t<a >\n\n\t\t\t\t<div class=\"gem-icon gem-icon-pack-fontawesome gem-icon-size-medium  gem-icon-shape-default \">\n\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"gem-icon-inner\">\t\t\t\t\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"padding-box-inner\">\t\n\t\t\t\t\t\t\t\t\t\t\t\n\n\n\t\t\t\t\t\n\t\t\t\t\t<span class=\"gem-icon-half-1\"><span class=\"back-angle\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"gem-elegant icon-puzzle\"><\/i>\t\t\t\t\t<\/span><\/span>\n\t\t\t\t\t<span class=\"gem-icon-half-2\"><span class=\"back-angle\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"gem-elegant icon-puzzle\"><\/i>\t\t\t\t\t<\/span><\/span>\t\n\t\t\t\t\n\t\t\t\t<\/div>\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t<\/div>\n\n\t\t\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f12072a flex-horizontal-align-default flex-horizontal-align-tablet-default flex-horizontal-align-mobile-default flex-vertical-align-default flex-vertical-align-tablet-default flex-vertical-align-mobile-default elementor-widget elementor-widget-heading\" data-id=\"f12072a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"title-h6 elementor-heading-title elementor-size-default\">People<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ac6f56 flex-horizontal-align-default flex-horizontal-align-tablet-default flex-horizontal-align-mobile-default flex-vertical-align-default flex-vertical-align-tablet-default flex-vertical-align-mobile-default elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"2ac6f56\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\r\n\t\t\t\t\t\t<p>Lorem ipsum dolor sit amet, consectetur adipisicing elit, sed do eiusmod tempor incididunt ut labore et dolore.<\/p>\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4eec0d2 flex-horizontal-align-default flex-horizontal-align-tablet-default flex-horizontal-align-mobile-default flex-vertical-align-default flex-vertical-align-tablet-default flex-vertical-align-mobile-default elementor-widget elementor-widget-spacer\" data-id=\"4eec0d2\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div><\/div>\r\n\t\t<\/section>\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div><\/div>\r\n\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e4cb361 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e4cb361\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\r\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-thegem\"><div class=\"elementor-row\">\r\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0a80f89\" data-id=\"0a80f89\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1eea2de flex-horizontal-align-default flex-horizontal-align-tablet-default flex-horizontal-align-mobile-default flex-vertical-align-default flex-vertical-align-tablet-default flex-vertical-align-mobile-default elementor-widget elementor-widget-heading\" data-id=\"1eea2de\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"title-h1 elementor-heading-title elementor-size-default\">Customers about us<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-04accc2 elementor-widget-divider--view-line flex-horizontal-align-default flex-horizontal-align-tablet-default flex-horizontal-align-mobile-default flex-vertical-align-default flex-vertical-align-tablet-default flex-vertical-align-mobile-default elementor-widget elementor-widget-divider\" data-id=\"04accc2\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b67cae elementor-widget__width-initial flex-horizontal-align-default flex-horizontal-align-tablet-default flex-horizontal-align-mobile-default flex-vertical-align-default flex-vertical-align-tablet-default flex-vertical-align-mobile-default elementor-widget elementor-widget-heading\" data-id=\"6b67cae\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"styled-subtitle elementor-heading-title elementor-size-default\">Lorem ipsum dolor sit amet, consectetur adipisicing elit,\nsed do eiusmod tempor incididunt ut labore et dolore<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-796a722 flex-horizontal-align-default flex-horizontal-align-tablet-default flex-horizontal-align-mobile-default flex-vertical-align-default flex-vertical-align-tablet-default flex-vertical-align-mobile-default elementor-widget elementor-widget-thegem-testimonials\" data-id=\"796a722\" data-element_type=\"widget\" data-settings=\"{&quot;thegem_elementor_preset&quot;:&quot;style2&quot;,&quot;content_testimonials_cat&quot;:[&quot;ts&quot;],&quot;skin_source&quot;:&quot;default&quot;,&quot;content_elems_img&quot;:&quot;yes&quot;,&quot;content_elems_name&quot;:&quot;yes&quot;,&quot;content_elems_position&quot;:&quot;yes&quot;,&quot;content_elems_company&quot;:&quot;yes&quot;,&quot;content_elems_quote&quot;:&quot;yes&quot;}\" data-widget_type=\"thegem-testimonials.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t\t<div class=\"preloader\">\n\t\t\t\t<div class=\"preloader-spin\"><\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"style2 gem-testimonials\n\t\t\t\t\t\t\"\n\t\t\t >\n\t\t\t\n\t\t\t\t\t\t\t<style>.gem-testimonials-navigation{display: block;}<\/style>\n\t\t\t\n\t\t\t\t\n<div id=\"post-173\" class=\"gem-testimonial-item post-173 thegem_testimonial type-thegem_testimonial status-publish has-post-thumbnail\">\n\t\t\t<div class=\"gem-testimonial-wrapper  \">\n\n\t\t\t\t\t\t\t<div class=\"gem-testimonial-image\">\n\t\t\t\t\t<span>\n\t\t\t\t\t\t<img width=\"400\" height=\"400\" src=\"https:\/\/tomatocrust.com\/wp-content\/uploads\/2019\/02\/Faces-400x400px-1_1_11-thegem-person.jpg\" class=\"img-responsive img-circle wp-post-image\" alt=\"\" srcset=\"https:\/\/tomatocrust.com\/wp-content\/uploads\/2019\/02\/Faces-400x400px-1_1_11-thegem-person-thegem-testimonial.jpg 2x\" sizes=\"100vw\" \/>\t\t\t\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"gem-testimonial-content\">\n\n\t\t\t\t\t\t\t<div class=\"gem-testimonial-name title-h6\">Jeniffer Burns<\/div>\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"gem-testimonial-position\">Creative Heads Inc.<\/div>\t\t\t\n\t\t\t\t<div class=\"gem-testimonial-text\">\n\t\t\t\t\t<p>Lorem ipsum dolor sit amet, consectetur adipisicing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam<\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t<\/div>\n\n\t<\/div>\n<div id=\"post-178\" class=\"gem-testimonial-item post-178 thegem_testimonial type-thegem_testimonial status-publish has-post-thumbnail\">\n\t\t\t<div class=\"gem-testimonial-wrapper  \">\n\n\t\t\t\t\t\t\t<div class=\"gem-testimonial-image\">\n\t\t\t\t\t<span>\n\t\t\t\t\t\t<img width=\"400\" height=\"400\" src=\"https:\/\/tomatocrust.com\/wp-content\/uploads\/2019\/02\/Faces-400x400px-1_1_05-thegem-person.jpg\" class=\"img-responsive img-circle wp-post-image\" alt=\"\" srcset=\"https:\/\/tomatocrust.com\/wp-content\/uploads\/2019\/02\/Faces-400x400px-1_1_05-thegem-person-thegem-testimonial.jpg 2x\" sizes=\"100vw\" \/>\t\t\t\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"gem-testimonial-content\">\n\n\t\t\t\t\t\t\t<div class=\"gem-testimonial-name title-h6\">Marcus Fields<\/div>\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"gem-testimonial-position\">Marketing Manager<\/div>\t\t\t\n\t\t\t\t<div class=\"gem-testimonial-text\">\n\t\t\t\t\t<p>Lorem ipsum dolor sit amet, consectetur adipisicing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam<\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t<\/div>\n\n\t<\/div>\n<div id=\"post-179\" class=\"gem-testimonial-item post-179 thegem_testimonial type-thegem_testimonial status-publish has-post-thumbnail\">\n\t\t\t<div class=\"gem-testimonial-wrapper  \">\n\n\t\t\t\t\t\t\t<div class=\"gem-testimonial-image\">\n\t\t\t\t\t<span>\n\t\t\t\t\t\t<img width=\"400\" height=\"400\" src=\"https:\/\/tomatocrust.com\/wp-content\/uploads\/2019\/02\/Faces-400x400px-1_1_30-thegem-person.jpg\" class=\"img-responsive img-circle wp-post-image\" alt=\"\" srcset=\"https:\/\/tomatocrust.com\/wp-content\/uploads\/2019\/02\/Faces-400x400px-1_1_30-thegem-person-thegem-testimonial.jpg 2x\" sizes=\"100vw\" \/>\t\t\t\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"gem-testimonial-content\">\n\n\t\t\t\t\t\t\t<div class=\"gem-testimonial-name title-h6\">Jeniffer Burns<\/div>\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"gem-testimonial-position\">Creative Heads Inc.<\/div>\t\t\t\n\t\t\t\t<div class=\"gem-testimonial-text\">\n\t\t\t\t\t<p>Lorem ipsum dolor sit amet, consectetur adipisicing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam<\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t<\/div>\n\n\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"testimonials_svg\"><svg width=\"100\" height=\"50\"><path d=\"M 0,-1 Q 45,5 50,50 Q 55,5 100,-1\" \/><\/svg><\/div>\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\t \n\n\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div><\/div>\r\n\t\t<\/section>\r\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>WE CREATE BEST PRODUCTS We Always Provide High Quality Products SPEED OPTIMIZATION Lorem ipsum dolor sit amet, con secte tur&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-fullwidth.php","meta":{"content-type":"","footnotes":""},"class_list":["post-605","page","type-page","status-publish"],"_links":{"self":[{"href":"https:\/\/tomatocrust.com\/index.php\/wp-json\/wp\/v2\/pages\/605","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tomatocrust.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/tomatocrust.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/tomatocrust.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tomatocrust.com\/index.php\/wp-json\/wp\/v2\/comments?post=605"}],"version-history":[{"count":0,"href":"https:\/\/tomatocrust.com\/index.php\/wp-json\/wp\/v2\/pages\/605\/revisions"}],"wp:attachment":[{"href":"https:\/\/tomatocrust.com\/index.php\/wp-json\/wp\/v2\/media?parent=605"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}